{"id":14989,"date":"2020-07-02T09:07:54","date_gmt":"2020-07-02T07:07:54","guid":{"rendered":"https:\/\/cortomaltese.com\/fr\/?p=14989"},"modified":"2020-07-02T09:11:28","modified_gmt":"2020-07-02T07:11:28","slug":"interview-avec-thierry-thomas","status":"publish","type":"post","link":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/","title":{"rendered":"Interview avec Thierry Thomas: Hugo Pratt, ce qu&#8217;il a laiss\u00e9 en moi est comme le sillage d\u2019une musique"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><h2>Thierry Thomas, vainqueur du prix Goncourt pour sa biographie sur Pratt, raconte son travail et son amiti\u00e9 avec le p\u00e8re de Corto Maltese : &#8220;C&#8217;\u00e9tait l&#8217;homme le plus libre que j&#8217;ai jamais connu&#8221;.<\/h2>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-first\" style=\"--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% ) * 0.33333333333333 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-person person fusion-person-left fusion-person-1 fusion-person-icon-top\" style=\"--awb-pic-style-color:#000000;--awb-pic-borderradius:0px;--awb-margin-top:0px;--awb-margin-right:0px;--awb-margin-bottom:0px;--awb-margin-left:0px;--awb-social-box-border-top:0px;--awb-social-box-border-right:0px;--awb-social-box-border-bottom:0px;--awb-social-box-border-left:0px;--awb-social-box-border-color:var(--awb-color3);--awb-social-box-border-color-hover:var(--awb-color4);--awb-social-box-colors-hover:rgba(232,232,232,0.8);--awb-social-icon-boxed-colors:#e8e8e8;--awb-social-icon-colors:#bebdbd;--awb-social-icon-colors-hover:rgba(190,189,189,0.8);\"><div class=\"person-shortcode-image-wrapper\"><div class=\"person-image-container hover-type-zoomin\" style=\"border:0px solid #f6f6f6;-webkit-border-radius:0px;-moz-border-radius:0px;border-radius:0px;\"><img decoding=\"async\" class=\"person-img img-responsive wp-image-14990\" width=\"5504\" height=\"6880\" src=\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg\" alt=\"Thierry Thomas\" srcset=\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas-200x250.jpg 200w, https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas-400x500.jpg 400w, https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas-600x750.jpg 600w, https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas-800x1000.jpg 800w, https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas-1200x1500.jpg 1200w, https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg 5504w\" sizes=\"(max-width: 800px) 100vw, 400px\" \/><\/div><\/div><div class=\"person-desc\"><div class=\"person-author\"><div class=\"person-author-wrapper\"><span class=\"person-name\">Thierry Thomas<\/span><span class=\"person-title\"><\/span><\/div><\/div><div class=\"person-content fusion-clearfix\">r\u00e9alisateur et auteur<\/div><\/div><\/div><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"385\" height=\"592\" title=\"Le Prix Goncourt de la biographie\" src=\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/9782246863595.jpg\" alt class=\"img-responsive wp-image-14975\" srcset=\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/9782246863595-200x308.jpg 200w, https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/9782246863595.jpg 385w\" sizes=\"(max-width: 800px) 100vw, 385px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-2\"><p>\u00e9diteur Grasset<\/p>\n<p><strong>Hugo Pratt, trait pour trait<\/strong><\/p>\n<div class=\"fusion-button-wrapper\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.grasset.fr\/livres\/hugo-pratt-trait-pour-trait-9782246863595\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Acheter<\/span><\/a><\/div>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_3 2_3 fusion-two-third fusion-column-last\" style=\"--awb-bg-size:cover;width:66.666666666667%;width:calc(66.666666666667% - ( ( 4% ) * 0.66666666666667 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-3\"><p><b><i>Thierry, c&#8217;est g\u00e9n\u00e9ralement le contraire, mais vous avez d&#8217;abord fait le film &#8220;Hugo Pratt, trait pour trait&#8221; et ensuite le livre qui porte le m\u00eame titre. Comment l&#8217;id\u00e9e est-elle n\u00e9e ?<\/i><\/b><\/p>\n<p>Mon \u00e9ditrice, Martine Saada, m\u2019avait rendu visite dans la salle de montage de ce film, o\u00f9 elle a d\u00e9couvert une montagne de carnet de notes. Elle m\u2019a demand\u00e9 le contenu de ces carnets, ce qu\u2019il y avait l\u00e0 de plus que dans le film. Puis, quelques jours plus tard, l\u2019id\u00e9e lui est venue de d\u00e9velopper ces notes pour en faire un livre. Mais sa proposition \u00e9tait assortie d\u2019une autre, car elle a ajout\u00e9\u00a0: &#8220;Je voudrais qu\u2019il y ait des parties de ce livre \u00e0 la premi\u00e8re personne, je veux que tu \u00e9crives \u2018\u2019Je\u2019\u2019\u2026\u00a0\u00bb Elle savait les difficult\u00e9s que j\u2019\u00e9prouve \u00e0 travailler en me prenant pour sujet, ma d\u00e9fiance envers toute forme d\u2019entreprise autobiographique. Entre autres raisons parce que l\u2019\u00e9criture th\u00e9\u00e2trale compte \u00e9norm\u00e9ment pour moi, comme une sorte de mod\u00e8le, et qu\u2019au th\u00e9\u00e2tre, bien s\u00fbr, il n\u2019y a de place que pour le \u00ab Je\u00a0\u00bb des personnages, non pour celui de l\u2019auteur. Elle devait consid\u00e9rer que c\u2019\u00e9tait un blocage absurde, qui m\u2019interdisait d\u2019\u00e9crire v\u00e9ritablement\u00a0; elle n\u2019avait pas tort. Toujours est-il que j\u2019ai \u00e9crit ce livre en faisant jour apr\u00e8s jour l\u2019exp\u00e9rience que je ne pouvais atteindre certaines v\u00e9rit\u00e9s in\u00e9dites au sujet de l\u2019art d\u2019Hugo, et partant de lui-m\u00eame, qu\u2019\u00e0 la condition d\u2019affronter cet enjeu d\u2019\u00e9criture.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><b><i>Gagner le prix Goncourt \u00e9tait-il surprenant ?<\/i><\/b><\/p>\n<p>Mon Dieu oui, j\u2019en suis rest\u00e9 bouche b\u00e9e. Bien s\u00fbr, c&#8217;est une reconnaissance de mon travail, mais c\u2019en est une aussi pour l\u2019art d\u2019Hugo et pour l&#8217;univers de la bande dessin\u00e9e. En France, il continue d\u2019exister, quoiqu\u2019on dise, un foss\u00e9 qui s\u00e9pare la culture officielle des moyens d\u2019expression populaires, dont la bande dessin\u00e9e fait \u00e9videmment partie. Non pas tellement dans le monde de l\u2019\u00e9cole, de l\u2019universit\u00e9\u00a0: l\u00e0, il est vrai que les choses ont chang\u00e9 depuis la fin des ann\u00e9es 60\u00a0: l\u2019histoire de la bande dessin\u00e9e et celle de ses grands auteurs est d\u00e9sormais renseign\u00e9e, document\u00e9e, Hugo comme Herg\u00e9 sont expos\u00e9s dans les plus prestigieux mus\u00e9es (l\u2019exposition de Lyon, r\u00e9cemment, \u00e9tait une merveille)\u00a0; mais dans celui de la litt\u00e9rature, tout simplement. La peinture, le cin\u00e9ma m\u00eame, ont inspir\u00e9 de nombreux \u00e9crivains, et parmi les plus grands, mais je ne vois pas beaucoup d\u2019exemples de projets litt\u00e9raires, je veux dire essentiellement litt\u00e9raires, ayant pris pour objet la bande dessin\u00e9e. Et puis, autre surprise, j\u2019ai re\u00e7u le prix \u00ab\u00a0de la biographie\u00a0\u00bb. Or mon livre n\u2019est pas exactement une biographie\u00a0; en tout cas elle ne l\u2019est pas au sens traditionnel du terme. M\u00eame si, finalement, je donne beaucoup d\u2019informations, en particulier sur cette part de la vie d\u2019Hugo qui \u00e9tait consacr\u00e9e au dessin. Mais il y a incontestablement beaucoup de diff\u00e9rences entre une biographie de type classique et celle-ci\u00a0: je ne m\u2019efface pas, mes sensations sont au contraire le fil rouge du r\u00e9cit\u00a0; je refuse de s\u00e9parer le r\u00e9el de l\u2019imaginaire et consid\u00e8re l\u2019\u0153uvre comme \u00e9tant la \u00ab\u00a0vraie vie\u00a0\u00bb de l\u2019artiste\u00a0; enfin je ne crois pas qu\u2019il soit utile de tout raconter d\u2019une existence, chronologiquement, scrupuleusement, ann\u00e9e apr\u00e8s ann\u00e9e\u00a0: il vaut beaucoup mieux, me semble-t-il, se concentrer sur un certain nombre de jours et d\u2019\u00e9v\u00e9nements qui me paraissent r\u00e9v\u00e9lateurs, \u00e9clairants. L\u2019essentiel, et au fond peut-\u00eatre la seule chose qui importe vraiment lorsque l\u2019on \u00e9crit, que ce soit une biographie ou une fiction, c\u2019est que la personne (ou le personnage) soit l\u00e0. Nous avons tous fait cette exp\u00e9rience assez \u00e9trange et plut\u00f4t d\u00e9sesp\u00e9rante\u00a0qui consiste \u00e0 lire de ces biographies qui se veulent \u00ab\u00a0d\u00e9finitives\u00a0\u00bb,\u00a0monumentales par le nombre de pages, l\u2019abondance et la pr\u00e9cision des informations, mais qui pourtant jamais ne donnent \u00e0 sentir une pr\u00e9sence\u00a0: tout y est, sauf l\u2019\u00eatre lui-m\u00eame. Sauf ce qui fait la vie, pr\u00e9cis\u00e9ment. Quelques amis m\u2019ont dit, apr\u00e8s avoir lu mon livre\u00a0: \u00ab\u00a0On le sent, il est l\u00e0.\u00a0\u00bb, et rien ne pouvait me faire plus plaisir. Et puis Hugo \u00e9tait l\u2019\u00eatre le plus libre que j\u2019ai jamais rencontr\u00e9, vraiment le plus libre, d\u2019une libert\u00e9 sid\u00e9rante, d\u00e9concertante bien souvent. De sorte que je me suis fait la r\u00e9flexion, immodestement peut-\u00eatre, inconsciemment s\u00fbrement, qu\u2019il \u00e9tait bien normal qu\u2019un peu de cette libert\u00e9 rejaillisse sur mon travail.<\/p>\n<p><b><i>Comment vous \u00eates-vous rencontr\u00e9s ?<\/i><\/b><\/p>\n<p>\u00c0 15 ans, je voulais devenir dessinateur de bandes dessin\u00e9es. J&#8217;avais lu les premiers <i>Corto<\/i>, j&#8217;\u00e9tais fascin\u00e9, et j&#8217;essayais de les reproduire. C&#8217;\u00e9tait en 1972, je suis all\u00e9 chez lui \u00e0 Malamocco \u00e0 Venise, avec mes essais de bande dessin\u00e9e, pour avoir son avis. Il m&#8217;a dit qu&#8217;il n&#8217;y avait aucun probl\u00e8me avec la technique : <i>&#8220;Si vous dessinez chaque jour, vous deviendrez dessinateur. Mais vous devez am\u00e9liorer votre fa\u00e7on de raconter, vous devez apprendre \u00e0 raconter simplement. Non parce que les lecteurs sont des imb\u00e9ciles, mais parce que les \u00e9diteurs le sont. Du reste Monsieur est \u00e9diteur.\u00a0\u00bb <\/i>a-t-il ajout\u00e9 en me d\u00e9signant la personne qui \u00e9tait avec lui. Et tous les deux ont ri.<\/p>\n<p><b><i>Vous \u00eates-vous revus depuis ce jour-l\u00e0 ?<\/i><\/b><\/p>\n<p>Oui, mais de fa\u00e7on intermittente. Je n\u2019\u00e9tais pas un ami proche. Et puis je me suis \u00e9loign\u00e9 de la bande dessin\u00e9e. Mais avec Hugo le temps, le passage du temps, d\u2019une certaine mani\u00e8re ne comptait pas. Je pouvais le revoir apr\u00e8s deux ans, et de nouveau, instantan\u00e9ment, c\u2019\u00e9tait comme \u00e0 Malamocco vingt ans plus t\u00f4t.<\/p>\n<p><b>Que vous a laiss\u00e9 l\u2019amiti\u00e9 avec Hugo ?<\/b><\/p>\n<p>Cette question, c\u2019est au fond le point de d\u00e9part de mon livre\u00a0: je ne retrouve Hugo que lorsque je contemple ses dessins \u2014 mieux\u00a0: son trait. Ce qu&#8217;il a laiss\u00e9 en moi est comme le sillage d\u2019une musique, je regarde ses traits de la m\u00eame fa\u00e7on que j\u2019\u00e9coute une musique aim\u00e9e, avec laquelle j\u2019ai travers\u00e9 les \u00e2ges de ma vie. Hugo, \u00e0 mes yeux, \u00e9tait tout entier contenu dans son trait, dans l\u2019indicible beaut\u00e9 de son trait \u2014 que j\u2019ai pourtant essay\u00e9 de dire.<\/p>\n<p><b>De Fabrizio Paladini<\/b><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":14990,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[71,70,64],"class_list":["post-14989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-journal","tag-hugo-pratt","tag-interview","tag-thierry-thomas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Interview avec Thierry Thomas: Hugo Pratt, le sillage d\u2019une musique<\/title>\n<meta name=\"description\" content=\"Interview avec Thierry Thomas: Hugo Pratt, a laiss\u00e9 le sillage d\u2019une musique, je regarde ses traits de la m\u00eame fa\u00e7on que j\u2019\u00e9coute une musique aim\u00e9e\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview avec Thierry Thomas: Hugo Pratt, le sillage d\u2019une musique\" \/>\n<meta property=\"og:description\" content=\"Interview avec Thierry Thomas: Hugo Pratt, a laiss\u00e9 le sillage d\u2019une musique, je regarde ses traits de la m\u00eame fa\u00e7on que j\u2019\u00e9coute une musique aim\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/\" \/>\n<meta property=\"og:site_name\" content=\"cortomaltese fran\u00e7ais\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T07:07:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-02T07:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5504\" \/>\n\t<meta property=\"og:image:height\" content=\"6880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Corto Maltese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Corto Maltese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/\",\"url\":\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/\",\"name\":\"Interview avec Thierry Thomas: Hugo Pratt, le sillage d\u2019une musique\",\"isPartOf\":{\"@id\":\"https:\/\/cortomaltese.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg\",\"datePublished\":\"2020-07-02T07:07:54+00:00\",\"dateModified\":\"2020-07-02T07:11:28+00:00\",\"author\":{\"@id\":\"https:\/\/cortomaltese.com\/fr\/#\/schema\/person\/5204dd292c3d1105df4b66cc0749217e\"},\"description\":\"Interview avec Thierry Thomas: Hugo Pratt, a laiss\u00e9 le sillage d\u2019une musique, je regarde ses traits de la m\u00eame fa\u00e7on que j\u2019\u00e9coute une musique aim\u00e9e\",\"breadcrumb\":{\"@id\":\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#primaryimage\",\"url\":\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg\",\"contentUrl\":\"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg\",\"width\":5504,\"height\":6880},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/cortomaltese.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview avec Thierry Thomas: Hugo Pratt, ce qu&#8217;il a laiss\u00e9 en moi est comme le sillage d\u2019une musique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cortomaltese.com\/fr\/#website\",\"url\":\"https:\/\/cortomaltese.com\/fr\/\",\"name\":\"cortomaltese fran\u00e7ais\",\"description\":\"Il sito ufficiale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cortomaltese.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/cortomaltese.com\/fr\/#\/schema\/person\/5204dd292c3d1105df4b66cc0749217e\",\"name\":\"Corto Maltese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cortomaltese.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2ad4be5824b38545bbca3ce52ffd9add?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2ad4be5824b38545bbca3ce52ffd9add?s=96&d=mm&r=g\",\"caption\":\"Corto Maltese\"},\"url\":\"https:\/\/cortomaltese.com\/fr\/author\/cortomaltese\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview avec Thierry Thomas: Hugo Pratt, le sillage d\u2019une musique","description":"Interview avec Thierry Thomas: Hugo Pratt, a laiss\u00e9 le sillage d\u2019une musique, je regarde ses traits de la m\u00eame fa\u00e7on que j\u2019\u00e9coute une musique aim\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/","og_locale":"fr_FR","og_type":"article","og_title":"Interview avec Thierry Thomas: Hugo Pratt, le sillage d\u2019une musique","og_description":"Interview avec Thierry Thomas: Hugo Pratt, a laiss\u00e9 le sillage d\u2019une musique, je regarde ses traits de la m\u00eame fa\u00e7on que j\u2019\u00e9coute une musique aim\u00e9e","og_url":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/","og_site_name":"cortomaltese fran\u00e7ais","article_published_time":"2020-07-02T07:07:54+00:00","article_modified_time":"2020-07-02T07:11:28+00:00","og_image":[{"width":5504,"height":6880,"url":"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg","type":"image\/jpeg"}],"author":"Corto Maltese","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Corto Maltese","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/","url":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/","name":"Interview avec Thierry Thomas: Hugo Pratt, le sillage d\u2019une musique","isPartOf":{"@id":"https:\/\/cortomaltese.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#primaryimage"},"image":{"@id":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#primaryimage"},"thumbnailUrl":"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg","datePublished":"2020-07-02T07:07:54+00:00","dateModified":"2020-07-02T07:11:28+00:00","author":{"@id":"https:\/\/cortomaltese.com\/fr\/#\/schema\/person\/5204dd292c3d1105df4b66cc0749217e"},"description":"Interview avec Thierry Thomas: Hugo Pratt, a laiss\u00e9 le sillage d\u2019une musique, je regarde ses traits de la m\u00eame fa\u00e7on que j\u2019\u00e9coute une musique aim\u00e9e","breadcrumb":{"@id":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#primaryimage","url":"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg","contentUrl":"https:\/\/cortomaltese.com\/fr\/wp-content\/uploads\/sites\/3\/Therry-Thomas.jpg","width":5504,"height":6880},{"@type":"BreadcrumbList","@id":"https:\/\/cortomaltese.com\/fr\/interview-avec-thierry-thomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cortomaltese.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Interview avec Thierry Thomas: Hugo Pratt, ce qu&#8217;il a laiss\u00e9 en moi est comme le sillage d\u2019une musique"}]},{"@type":"WebSite","@id":"https:\/\/cortomaltese.com\/fr\/#website","url":"https:\/\/cortomaltese.com\/fr\/","name":"cortomaltese fran\u00e7ais","description":"Il sito ufficiale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cortomaltese.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cortomaltese.com\/fr\/#\/schema\/person\/5204dd292c3d1105df4b66cc0749217e","name":"Corto Maltese","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cortomaltese.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2ad4be5824b38545bbca3ce52ffd9add?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad4be5824b38545bbca3ce52ffd9add?s=96&d=mm&r=g","caption":"Corto Maltese"},"url":"https:\/\/cortomaltese.com\/fr\/author\/cortomaltese\/"}]}},"_links":{"self":[{"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/posts\/14989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/comments?post=14989"}],"version-history":[{"count":0,"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/posts\/14989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/media\/14990"}],"wp:attachment":[{"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/media?parent=14989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/categories?post=14989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cortomaltese.com\/fr\/wp-json\/wp\/v2\/tags?post=14989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}